{"id":24510,"date":"2019-11-28T16:26:04","date_gmt":"2019-11-28T14:26:04","guid":{"rendered":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee"},"modified":"2026-05-07T15:16:48","modified_gmt":"2026-05-07T13:16:48","slug":"ueberlingen-bodensee","status":"publish","type":"wpsl_stores","link":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/","title":{"rendered":"\u00dcberlingen (Bodensee)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"template":"","wpsl_store_category":[1502],"class_list":["post-24510","wpsl_stores","type-wpsl_stores","status-publish","hentry","wpsl_store_category-baden-wuerttemberg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finanzamt \u00dcberlingen (Bodensee): \u00d6ffnungszeiten, Adresse &amp; Telefon - smartsteuer<\/title>\n<meta name=\"description\" content=\"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberlingen (Bodensee)\" \/>\n<meta property=\"og:description\" content=\"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/\" \/>\n<meta property=\"og:site_name\" content=\"smartsteuer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/smartsteuer\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T13:16:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@smartsteuer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/finanzamt\\\/ueberlingen-bodensee\\\/\",\"url\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/finanzamt\\\/ueberlingen-bodensee\\\/\",\"name\":\"Finanzamt \u00dcberlingen (Bodensee): \u00d6ffnungszeiten, Adresse & Telefon - smartsteuer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#website\"},\"datePublished\":\"2019-11-28T14:26:04+00:00\",\"dateModified\":\"2026-05-07T13:16:48+00:00\",\"description\":\"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/finanzamt\\\/ueberlingen-bodensee\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/finanzamt\\\/ueberlingen-bodensee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/finanzamt\\\/ueberlingen-bodensee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberlingen (Bodensee)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#website\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/\",\"name\":\"smartsteuer\",\"description\":\"Steuererkl\u00e4rung 2021 online machen &amp; Steuern sparen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#organization\",\"name\":\"smartsteuer GmbH\",\"url\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/smartsteuer-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.k8s.stage.smartsteuer.dev\\\/online\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/smartsteuer-logo.png\",\"width\":250,\"height\":94,\"caption\":\"smartsteuer GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.smartsteuer.de\\\/online\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/smartsteuer\\\/\",\"https:\\\/\\\/x.com\\\/smartsteuer\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCu02GkFNrMRzwysT2SEmNrQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finanzamt \u00dcberlingen (Bodensee): \u00d6ffnungszeiten, Adresse & Telefon - smartsteuer","description":"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberlingen (Bodensee)","og_description":"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713","og_url":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/","og_site_name":"smartsteuer","article_publisher":"https:\/\/de-de.facebook.com\/smartsteuer\/","article_modified_time":"2026-05-07T13:16:48+00:00","twitter_card":"summary_large_image","twitter_site":"@smartsteuer","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/","url":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/","name":"Finanzamt \u00dcberlingen (Bodensee): \u00d6ffnungszeiten, Adresse & Telefon - smartsteuer","isPartOf":{"@id":"https:\/\/www.smartsteuer.de\/online\/#website"},"datePublished":"2019-11-28T14:26:04+00:00","dateModified":"2026-05-07T13:16:48+00:00","description":"Alle Informationen zum Finanzamt \u00dcberlingen (Bodensee) mit der Finanzamtsnummer 2887 auf einem Blick \u25bb Adresse, Telefon, \u00d6ffnungszeiten! \u2713","breadcrumb":{"@id":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/finanzamt\/ueberlingen-bodensee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/"},{"@type":"ListItem","position":2,"name":"\u00dcberlingen (Bodensee)"}]},{"@type":"WebSite","@id":"https:\/\/www.smartsteuer.de\/online\/#website","url":"https:\/\/www.smartsteuer.de\/online\/","name":"smartsteuer","description":"Steuererkl\u00e4rung 2021 online machen &amp; Steuern sparen","publisher":{"@id":"https:\/\/www.smartsteuer.de\/online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.smartsteuer.de\/online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.smartsteuer.de\/online\/#organization","name":"smartsteuer GmbH","url":"https:\/\/www.smartsteuer.de\/online\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.smartsteuer.de\/online\/#\/schema\/logo\/image\/","url":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-content\/uploads\/2018\/10\/smartsteuer-logo.png","contentUrl":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-content\/uploads\/2018\/10\/smartsteuer-logo.png","width":250,"height":94,"caption":"smartsteuer GmbH"},"image":{"@id":"https:\/\/www.smartsteuer.de\/online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/smartsteuer\/","https:\/\/x.com\/smartsteuer","https:\/\/www.youtube.com\/channel\/UCu02GkFNrMRzwysT2SEmNrQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/wpsl_stores\/24510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/wpsl_stores"}],"about":[{"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/types\/wpsl_stores"}],"version-history":[{"count":1,"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/wpsl_stores\/24510\/revisions"}],"predecessor-version":[{"id":32483,"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/wpsl_stores\/24510\/revisions\/32483"}],"wp:attachment":[{"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/media?parent=24510"}],"wp:term":[{"taxonomy":"wpsl_store_category","embeddable":true,"href":"https:\/\/www.k8s.stage.smartsteuer.dev\/online\/wp-json\/wp\/v2\/wpsl_store_category?post=24510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}